{"id":3266,"date":"2025-05-30T13:16:40","date_gmt":"2025-05-30T11:16:40","guid":{"rendered":"https:\/\/www.agri-pdb.org\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/"},"modified":"2025-11-05T14:41:27","modified_gmt":"2025-11-05T13:41:27","slug":"participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb","status":"publish","type":"post","link":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/","title":{"rendered":"Participez \u00e0 la nouvelle enqu\u00eate de la plateforme Agri-PDB"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"host-lopnbnfpjmgpbppclhclehhgafnifija\" style=\"position: relative; z-index: 2147483647;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":9,"featured_media":3248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[155],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Participez \u00e0 la nouvelle enqu\u00eate de la plateforme Agri-PDB - Agri-PDB<\/title>\n<meta name=\"description\" content=\"Participez \u00e0 l&#039;enqu\u00eate 2025 de la plateforme Agri-PDB pour contribuer \u00e0 orienter le soutien futur \u00e0 l\u2019agriculture durable ! Partagez vos id\u00e9es et guidez des actions concr\u00e8tes au sein de la communaut\u00e9 mondiale des banques publiques de d\u00e9veloppement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Participez \u00e0 la nouvelle enqu\u00eate de la plateforme Agri-PDB - Agri-PDB\" \/>\n<meta property=\"og:description\" content=\"Participez \u00e0 l&#039;enqu\u00eate 2025 de la plateforme Agri-PDB pour contribuer \u00e0 orienter le soutien futur \u00e0 l\u2019agriculture durable ! Partagez vos id\u00e9es et guidez des actions concr\u00e8tes au sein de la communaut\u00e9 mondiale des banques publiques de d\u00e9veloppement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/\" \/>\n<meta property=\"og:site_name\" content=\"Agri-PDB\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T11:16:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T13:41:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.agri-pdb.org\/wp-content\/uploads\/2025\/05\/survey-e1748604927138.png\" \/>\n\t<meta property=\"og:image:width\" content=\"637\" \/>\n\t<meta property=\"og:image:height\" content=\"546\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yue Hu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yue Hu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/\",\"url\":\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/\",\"name\":\"Participez \u00e0 la nouvelle enqu\u00eate de la plateforme Agri-PDB - Agri-PDB\",\"isPartOf\":{\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.agri-pdb.org\/wp-content\/uploads\/2025\/05\/survey-e1748604927138.png\",\"datePublished\":\"2025-05-30T11:16:40+00:00\",\"dateModified\":\"2025-11-05T13:41:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/#\/schema\/person\/378c606d90389c402e17ddefe54a7092\"},\"description\":\"Participez \u00e0 l'enqu\u00eate 2025 de la plateforme Agri-PDB pour contribuer \u00e0 orienter le soutien futur \u00e0 l\u2019agriculture durable ! Partagez vos id\u00e9es et guidez des actions concr\u00e8tes au sein de la communaut\u00e9 mondiale des banques publiques de d\u00e9veloppement.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#primaryimage\",\"url\":\"https:\/\/www.agri-pdb.org\/wp-content\/uploads\/2025\/05\/survey-e1748604927138.png\",\"contentUrl\":\"https:\/\/www.agri-pdb.org\/wp-content\/uploads\/2025\/05\/survey-e1748604927138.png\",\"width\":637,\"height\":546},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.agri-pdb.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participez \u00e0 la nouvelle enqu\u00eate de la plateforme Agri-PDB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/#website\",\"url\":\"https:\/\/www.agri-pdb.org\/fr\/\",\"name\":\"Agri-PDB\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.agri-pdb.org\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.agri-pdb.org\/fr\/#\/schema\/person\/378c606d90389c402e17ddefe54a7092\",\"name\":\"Yue Hu\",\"url\":\"https:\/\/www.agri-pdb.org\/fr\/author\/yue\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Participez \u00e0 la nouvelle enqu\u00eate de la plateforme Agri-PDB - Agri-PDB","description":"Participez \u00e0 l'enqu\u00eate 2025 de la plateforme Agri-PDB pour contribuer \u00e0 orienter le soutien futur \u00e0 l\u2019agriculture durable ! Partagez vos id\u00e9es et guidez des actions concr\u00e8tes au sein de la communaut\u00e9 mondiale des banques publiques de d\u00e9veloppement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/","og_locale":"fr_FR","og_type":"article","og_title":"Participez \u00e0 la nouvelle enqu\u00eate de la plateforme Agri-PDB - Agri-PDB","og_description":"Participez \u00e0 l'enqu\u00eate 2025 de la plateforme Agri-PDB pour contribuer \u00e0 orienter le soutien futur \u00e0 l\u2019agriculture durable ! Partagez vos id\u00e9es et guidez des actions concr\u00e8tes au sein de la communaut\u00e9 mondiale des banques publiques de d\u00e9veloppement.","og_url":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/","og_site_name":"Agri-PDB","article_published_time":"2025-05-30T11:16:40+00:00","article_modified_time":"2025-11-05T13:41:27+00:00","og_image":[{"width":637,"height":546,"url":"https:\/\/www.agri-pdb.org\/wp-content\/uploads\/2025\/05\/survey-e1748604927138.png","type":"image\/png"}],"author":"Yue Hu","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Yue Hu","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/","url":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/","name":"Participez \u00e0 la nouvelle enqu\u00eate de la plateforme Agri-PDB - Agri-PDB","isPartOf":{"@id":"https:\/\/www.agri-pdb.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#primaryimage"},"image":{"@id":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.agri-pdb.org\/wp-content\/uploads\/2025\/05\/survey-e1748604927138.png","datePublished":"2025-05-30T11:16:40+00:00","dateModified":"2025-11-05T13:41:27+00:00","author":{"@id":"https:\/\/www.agri-pdb.org\/fr\/#\/schema\/person\/378c606d90389c402e17ddefe54a7092"},"description":"Participez \u00e0 l'enqu\u00eate 2025 de la plateforme Agri-PDB pour contribuer \u00e0 orienter le soutien futur \u00e0 l\u2019agriculture durable ! Partagez vos id\u00e9es et guidez des actions concr\u00e8tes au sein de la communaut\u00e9 mondiale des banques publiques de d\u00e9veloppement.","breadcrumb":{"@id":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#primaryimage","url":"https:\/\/www.agri-pdb.org\/wp-content\/uploads\/2025\/05\/survey-e1748604927138.png","contentUrl":"https:\/\/www.agri-pdb.org\/wp-content\/uploads\/2025\/05\/survey-e1748604927138.png","width":637,"height":546},{"@type":"BreadcrumbList","@id":"https:\/\/www.agri-pdb.org\/fr\/participez-a-la-nouvelle-enquete-de-la-plateforme-agri-pdb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.agri-pdb.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Participez \u00e0 la nouvelle enqu\u00eate de la plateforme Agri-PDB"}]},{"@type":"WebSite","@id":"https:\/\/www.agri-pdb.org\/fr\/#website","url":"https:\/\/www.agri-pdb.org\/fr\/","name":"Agri-PDB","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.agri-pdb.org\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.agri-pdb.org\/fr\/#\/schema\/person\/378c606d90389c402e17ddefe54a7092","name":"Yue Hu","url":"https:\/\/www.agri-pdb.org\/fr\/author\/yue\/"}]}},"_links":{"self":[{"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/posts\/3266"}],"collection":[{"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/comments?post=3266"}],"version-history":[{"count":2,"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/posts\/3266\/revisions"}],"predecessor-version":[{"id":3786,"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/posts\/3266\/revisions\/3786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/media\/3248"}],"wp:attachment":[{"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/media?parent=3266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/categories?post=3266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agri-pdb.org\/fr\/wp-json\/wp\/v2\/tags?post=3266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}